{"id":14921,"date":"2025-12-09T09:52:35","date_gmt":"2025-12-09T08:52:35","guid":{"rendered":"https:\/\/www.nidek.fr\/?p=14921"},"modified":"2025-12-09T09:52:49","modified_gmt":"2025-12-09T08:52:49","slug":"nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest","status":"publish","type":"post","link":"https:\/\/www.nidek.fr\/en\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/","title":{"rendered":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest"},"content":{"rendered":"<p><strong> NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest<\/strong><\/p>\n<p>Nous sommes heureux et fiers d\u2019annoncer que <strong>NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de Saint-Priest<\/strong> lors de la c\u00e9r\u00e9monie de cl\u00f4ture du <em>Mois de l\u2019\u00c9conomie 2025<\/em>.<br \/>\nCette distinction honore notre <strong>ancrage local<\/strong>, notre <strong>expertise industrielle<\/strong> et le r\u00f4le central de notre <strong>site de production de Saint-Priest<\/strong>, v\u00e9ritable c\u0153ur technologique de NIDEK en France.<\/p>\n<p><strong>Le site industriel de Saint-Priest : un savoir-faire unique<\/strong><br \/>\nNotre usine de Saint-Priest joue un r\u00f4le strat\u00e9gique pour NIDEK :<\/p>\n<ul>\n<li><strong>Assemblage et production<\/strong> de technologies majeures d\u00e9di\u00e9es \u00e0 l\u2019optique et \u00e0 l\u2019ophtalmologie ;<\/li>\n<li>Accueil de nos <strong>\u00e9quipes R&amp;D et techniques<\/strong>, qui d\u00e9veloppent chaque jour des solutions innovantes et fiables.<\/li>\n<li>Un savoir-faire local qui contribue chaque jour \u00e0 l\u2019innovation et \u00e0 la fiabilit\u00e9 des solutions NIDEK.<\/li>\n<\/ul>\n<p><strong>Pourquoi NIDEK SA a \u00e9t\u00e9 r\u00e9compens\u00e9e ?<\/strong><\/p>\n<p>La Ville de Saint-Priest distingue chaque ann\u00e9e des entreprises qui incarnent le <strong>dynamisme \u00e9conomique<\/strong> du territoire parmi pr\u00e8s de 5 000 acteurs locaux.<br \/>\nLes crit\u00e8res retenus mettent en avant :<\/p>\n<ul>\n<li>Une <strong>implantation durable et active<\/strong> sur la commune,<\/li>\n<li>La valorisation de <strong>proc\u00e9d\u00e9s et technologies industrielles<\/strong> remarquables,<\/li>\n<li>L\u2019innovation<strong>, la performance et la qualit\u00e9 de production<\/strong>,<\/li>\n<\/ul>\n<p>Nous sommes honor\u00e9s d\u2019avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9s par les \u00e9lus et la Direction \u00c9conomie-Emploi, et nous partageons cette distinction avec <strong>toutes les \u00e9quipes de NIDEK<\/strong>, en France comme au Japon.<\/p>\n<p>Nous adressons nos plus sinc\u00e8res remerciements \u00e0 <strong>Monsieur le Maire et \u00e0 la Mairie de Saint-Priest<\/strong> pour cet honneur, et remercions nos \u00e9quipes pour leur engagement quotidien qui rend cette reconnaissance possible.<\/p>\n<p><strong>Des photos de l\u2019\u00e9v\u00e9nement sont d\u00e9j\u00e0 disponibles<\/strong>, et une <strong>vid\u00e9o r\u00e9alis\u00e9e par la Ville<\/strong>, pr\u00e9sentant NIDEK et notre usine de Saint-Priest est \u00e9galement <a href=\"https:\/\/youtu.be\/wOMPqSWIUeU\">diffus\u00e9e en cliquant ici<\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-14922\" src=\"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg\" alt=\"\" width=\"4032\" height=\"3024\" srcset=\"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg 4032w, https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39-1536x1152.jpeg 1536w, https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39-2048x1536.jpeg 2048w, https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39-16x12.jpeg 16w\" sizes=\"(max-width: 4032px) 100vw, 4032px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14923\" src=\"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-26-sur-39.jpeg\" alt=\"\" width=\"4032\" height=\"3024\" srcset=\"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-26-sur-39.jpeg 4032w, https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-26-sur-39-1536x1152.jpeg 1536w, https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-26-sur-39-2048x1536.jpeg 2048w, https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-26-sur-39-16x12.jpeg 16w\" sizes=\"(max-width: 4032px) 100vw, 4032px\" \/><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de Saint-Priest lors de la c\u00e9r\u00e9monie de cl\u00f4ture du Mois de l\u2019\u00c9conomie 2025. Cette distinction honore notre ancrage local, notre expertise industrielle et le r\u00f4le central de notre [&hellip;]<\/p>","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12,11],"tags":[],"class_list":["post-14921","post","type-post","status-publish","format-standard","hentry","category-blog","category-evenements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest - NIDEK France<\/title>\n<meta name=\"description\" content=\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nidek.fr\/en\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest - NIDEK France\" \/>\n<meta property=\"og:description\" content=\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nidek.fr\/en\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/\" \/>\n<meta property=\"og:site_name\" content=\"NIDEK France\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T08:52:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T08:52:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Topuzoglu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tech@trafic-influence.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Topuzoglu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/\"},\"author\":{\"name\":\"Thomas Topuzoglu\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/#\\\/schema\\\/person\\\/66054007a07703e4531a1dd51a0d3b45\"},\"headline\":\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest\",\"datePublished\":\"2025-12-09T08:52:35+00:00\",\"dateModified\":\"2025-12-09T08:52:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/\"},\"wordCount\":324,\"image\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nidek.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/RIE-2025-22-sur-39.jpeg\",\"articleSection\":[\"Blog\",\"\u00c9v\u00e8nements\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/\",\"url\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/\",\"name\":\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest - NIDEK France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nidek.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/RIE-2025-22-sur-39.jpeg\",\"datePublished\":\"2025-12-09T08:52:35+00:00\",\"dateModified\":\"2025-12-09T08:52:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/#\\\/schema\\\/person\\\/66054007a07703e4531a1dd51a0d3b45\"},\"description\":\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nidek.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/RIE-2025-22-sur-39.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.nidek.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/RIE-2025-22-sur-39.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.nidek.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.nidek.fr\\\/\",\"name\":\"NIDEK France\",\"description\":\"The Art of Eye Care\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nidek.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nidek.fr\\\/#\\\/schema\\\/person\\\/66054007a07703e4531a1dd51a0d3b45\",\"name\":\"Thomas Topuzoglu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92b13846a5f3697c2b12c8825d8c12370af89a597ee708451d00371fdd1eedf0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92b13846a5f3697c2b12c8825d8c12370af89a597ee708451d00371fdd1eedf0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92b13846a5f3697c2b12c8825d8c12370af89a597ee708451d00371fdd1eedf0?s=96&d=mm&r=g\",\"caption\":\"Thomas Topuzoglu\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/tech@trafic-influence.com\"],\"url\":\"https:\\\/\\\/www.nidek.fr\\\/en\\\/author\\\/ttopuzoglu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest - NIDEK France","description":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nidek.fr\/en\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/","og_locale":"en_GB","og_type":"article","og_title":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest - NIDEK France","og_description":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de","og_url":"https:\/\/www.nidek.fr\/en\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/","og_site_name":"NIDEK France","article_published_time":"2025-12-09T08:52:35+00:00","article_modified_time":"2025-12-09T08:52:49+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg","type":"image\/jpeg"}],"author":"Thomas Topuzoglu","twitter_card":"summary_large_image","twitter_creator":"@tech@trafic-influence.com","twitter_misc":{"Written by":"Thomas Topuzoglu","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#article","isPartOf":{"@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/"},"author":{"name":"Thomas Topuzoglu","@id":"https:\/\/www.nidek.fr\/#\/schema\/person\/66054007a07703e4531a1dd51a0d3b45"},"headline":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest","datePublished":"2025-12-09T08:52:35+00:00","dateModified":"2025-12-09T08:52:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/"},"wordCount":324,"image":{"@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg","articleSection":["Blog","\u00c9v\u00e8nements"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/","url":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/","name":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest - NIDEK France","isPartOf":{"@id":"https:\/\/www.nidek.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#primaryimage"},"image":{"@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg","datePublished":"2025-12-09T08:52:35+00:00","dateModified":"2025-12-09T08:52:49+00:00","author":{"@id":"https:\/\/www.nidek.fr\/#\/schema\/person\/66054007a07703e4531a1dd51a0d3b45"},"description":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest Nous sommes heureux et fiers d\u2019annoncer que NIDEK SA a \u00e9t\u00e9 distingu\u00e9e par la Ville de","breadcrumb":{"@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#primaryimage","url":"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg","contentUrl":"https:\/\/www.nidek.fr\/wp-content\/uploads\/2025\/12\/RIE-2025-22-sur-39.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nidek.fr\/nidek-sa-laureate-du-mois-de-leconomie-de-la-ville-de-saint-priest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.nidek.fr\/"},{"@type":"ListItem","position":2,"name":"NIDEK SA Laur\u00e9ate du Mois de l\u2019\u00c9conomie de la Ville de Saint-Priest"}]},{"@type":"WebSite","@id":"https:\/\/www.nidek.fr\/#website","url":"https:\/\/www.nidek.fr\/","name":"NIDEK France","description":"The Art of Eye Care","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nidek.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.nidek.fr\/#\/schema\/person\/66054007a07703e4531a1dd51a0d3b45","name":"Thomas Topuzoglu","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/92b13846a5f3697c2b12c8825d8c12370af89a597ee708451d00371fdd1eedf0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92b13846a5f3697c2b12c8825d8c12370af89a597ee708451d00371fdd1eedf0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92b13846a5f3697c2b12c8825d8c12370af89a597ee708451d00371fdd1eedf0?s=96&d=mm&r=g","caption":"Thomas Topuzoglu"},"sameAs":["https:\/\/x.com\/tech@trafic-influence.com"],"url":"https:\/\/www.nidek.fr\/en\/author\/ttopuzoglu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/posts\/14921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/comments?post=14921"}],"version-history":[{"count":2,"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/posts\/14921\/revisions"}],"predecessor-version":[{"id":14925,"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/posts\/14921\/revisions\/14925"}],"wp:attachment":[{"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/media?parent=14921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/categories?post=14921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nidek.fr\/en\/wp-json\/wp\/v2\/tags?post=14921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}